{"id":58633,"date":"2019-01-15T07:51:30","date_gmt":"2019-01-15T13:51:30","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=58633"},"modified":"2019-01-15T07:51:38","modified_gmt":"2019-01-15T13:51:38","slug":"al-menos-7-estados-con-comercio-huachicol","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/al-menos-7-estados-con-comercio-huachicol\/","title":{"rendered":"Al menos 7 Estados con comercio huachicol"},"content":{"rendered":"\n<p>Por instrucci\u00f3n del Presidente \u00c1ndres Manuel L\u00f3pez Obrador,  <br>\u00a0la Administraci\u00f3n General de la Auditor\u00eda Fiscal de la Federaci\u00f3n del\u00a0Servicio de Administraci\u00f3n Tributaria (SAT) solicit\u00f3 a Petr\u00f3leos Mexicanos (PEMEX) su reporte de Ejercicio Fiscal 2017, el resultado fue que 194 gasolineras registran &#8220;inconsistencias&#8221; fiscales por 3 mil 217 millones de pesos.<\/p>\n\n\n\n<p>De acuerdo a Margarita R\u00edos Farjat, la investigaci\u00f3n se\u00f1al\u00f3 que el 54% de estas inconsistencias fiscales se registran en tan solo 7 Estados:  <br>Ciudad de M\u00e9xico, Michoac\u00e1n, Estado de M\u00e9xico, Tamaulipas, Baja California, Jalisco y Puebla.<\/p>\n\n\n\n<p>Cabe mencionar que como parte de la investigaci\u00f3n se encontr\u00f3 que al menos 32 contribuyentes registran robo de hidrocarburos y otros 200 est\u00e1n siendo investigados por estos mismos delitos; por lo que se realizar\u00edan diversos operativos como parte de las acciones de investigaci\u00f3n. <\/p>\n\n\n\n<p>R\u00edos Farjat indic\u00f3 que la investigaci\u00f3n no ha concluido pues ahora sigue el tema de recuperar los recursos fiscales no declarados en  <br>pr\u00e1ctica asociadas al transporte y almacenamiento de combustible.<\/p>\n\n\n\n<p>En este sentido, el titular de la  Unidad de Inteligencia Financiera de la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SHCP),  Santiago Nieto Castillo se\u00f1al\u00f3 que la investigaci\u00f3n realizada hasta el momento a revelado 14 reportes de operaciones inusuales y relevantes, donde los casos m\u00e1s sobresalientes en el comercio huachicolero son el de un expresidente Municipal; un empresario y un exfuncionario de PEMEX; aunque no dio nombres si indic\u00f3 que la investigaci\u00f3n continuar\u00e1. <\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Al menos 7 Estados con comercio huachicol' data-link='https:\/\/visionpeninsular.com\/mid\/al-menos-7-estados-con-comercio-huachicol\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Por instrucci\u00f3n del Presidente \u00c1ndres Manuel L\u00f3pez Obrador, \u00a0la Administraci\u00f3n General de la Auditor\u00eda Fiscal de la Federaci\u00f3n del\u00a0Servicio de Administraci\u00f3n Tributaria (SAT) solicit\u00f3 a Petr\u00f3leos Mexicanos (PEMEX) su reporte de Ejercicio Fiscal 2017, el resultado fue que 194 gasolineras registran &#8220;inconsistencias&#8221; fiscales por 3 mil 217 millones de pesos. De acuerdo a Margarita R\u00edos &hellip;<\/p>\n","protected":false},"author":1,"featured_media":58674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[50],"tags":[79],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/58633"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=58633"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/58633\/revisions"}],"predecessor-version":[{"id":58675,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/58633\/revisions\/58675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/58674"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=58633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=58633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=58633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}