{"id":35069,"date":"2018-01-10T10:59:07","date_gmt":"2018-01-10T16:59:07","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=35069"},"modified":"2018-01-10T10:59:07","modified_gmt":"2018-01-10T16:59:07","slug":"cobijan-a-personas-vulnerables-kanasin","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/cobijan-a-personas-vulnerables-kanasin\/","title":{"rendered":"\u201cCobijan\u201d a personas vulnerables de Kanas\u00edn"},"content":{"rendered":"<p>Ante el inicio de la temporada de bajas temperaturas, el Ayuntamiento de Kanas\u00edn, a trav\u00e9s del Gobierno del Estado, entreg\u00f3 500 cobertores para adultos mayores y personas con alguna discapacidad en el municipio como parte del programa \u201cBienestar Invernal\u201d.<\/p>\n<p>Durante su intervenci\u00f3n, el alcalde Carlos Moreno Maga\u00f1a, indic\u00f3 que por instrucciones del Gobernador Rolando Zapata Bello, se est\u00e1n haciendo llegar los apoyos a este sector de la poblaci\u00f3n m\u00e1s vulnerable para que tengan con que protegerse del fr\u00edo y as\u00ed evitar enfermedades respiratorias.<\/p>\n<p>\u2014Agradecemos que este apoyo sea destinado para nuestros adultos mayores y personas con alguna discapacidad, pues es un sector vulnerable que requiere de nuestra protecci\u00f3n y ayuda en la temporada invernal por la baja de temperaturas\u2014afirm\u00f3<\/p>\n<p>Moreno Maga\u00f1a explic\u00f3 que en los pr\u00f3ximos d\u00edas, personal del ayuntamiento y de la Secretar\u00eda de Desarrollo Social repartir\u00e1n 2 mil cobertores en las diversas colonias, fraccionamientos y en las tres comisar\u00edas del municipio.<\/p>\n<p>\u2014Queremos que ustedes sepan que son importantes para nosotros, que la seguridad de ustedes es una prioridad en el municipio y con este apoyo, estamos sosteniendo la palabra de hacer lo necesario para beneficio de los adultos mayores y personas con discapacidad\u2014dijo<\/p>\n<p>Por su parte, la beneficiaria Mar\u00eda del Carmen Oxte G\u00f3mez, expres\u00f3 su gratitud y afirm\u00f3 que para ellos representa una gran ayuda, toda vez que debido a los materiales de construcci\u00f3n de algunas viviendas estas son sumamente fr\u00edas, sobre todo por las madrugadas, lo que les genera enfermedades en v\u00edas respiratorias principalmente.<\/p>\n<p>\u2014Muchos de nosotros no tenemos para comprar una cobija, por eso la importancia de estas entregas, ya que las bajas temperaturas nos provocan enfermedades y esto representa un gasto para nosotros\u2014 expres\u00f3.<\/p>\n<p>Al hacer la entrega de los cobertores, la directora del Instituto de Seguridad Social de los Trabajadores del Estado, Isstey, Gabriela C\u00e1ceres Vergara, en representaci\u00f3n del Gobernador, dijo que por sexto a\u00f1o consecutivo se trabaja hombro a hombro con los ayuntamientos para beneficiar a las personas que m\u00e1s lo necesitan.<\/p>\n<p>\u2014La mejor forma para que a todos nos vaya bien es unir esfuerzos y trabajar en un solo sentido para el desarrollo arm\u00f3nico de nuestra gente, sobretodo de las personas m\u00e1s vulnerables\u2014expres\u00f3.<\/p>\n<p>Al concluir el evento protocolario, personal del Ayuntamiento y de Sedesol estatal inici\u00f3 con la entrega de los cobertores en el polifuncional de Kanas\u00edn donde se dieron cita los primeros 500 beneficiarios.<\/p>\n<p>Para que las personas puedan acceder a este beneficio es necesario que lleven la copia de su INE con direcci\u00f3n de Kanas\u00edn.<\/p>\n<p>&nbsp;<\/p>\n<p>\u200b<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\u201cCobijan\u201d a personas vulnerables de Kanas\u00edn' data-link='https:\/\/visionpeninsular.com\/mid\/cobijan-a-personas-vulnerables-kanasin\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ante el inicio de la temporada de bajas temperaturas, el Ayuntamiento de Kanas\u00edn, a trav\u00e9s del Gobierno del Estado, entreg\u00f3 500 cobertores para adultos mayores y personas con alguna discapacidad en el municipio como parte del programa \u201cBienestar Invernal\u201d. Durante su intervenci\u00f3n, el alcalde Carlos Moreno Maga\u00f1a, indic\u00f3 que por instrucciones del Gobernador Rolando Zapata &hellip;<\/p>\n","protected":false},"author":5,"featured_media":35070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[50,37],"tags":[9634,9633,1499,9423],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/35069"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=35069"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/35069\/revisions"}],"predecessor-version":[{"id":35071,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/35069\/revisions\/35071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/35070"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=35069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=35069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=35069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}