{"id":2191,"date":"2016-04-21T09:37:46","date_gmt":"2016-04-21T14:37:46","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=2191"},"modified":"2016-04-21T09:38:21","modified_gmt":"2016-04-21T14:38:21","slug":"2191","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/2191\/","title":{"rendered":"Mauricio Vila entrega nuevo parque vehicular a Obras P\u00fablicas y Servicios P\u00fablicos Municipales &#8211; Inversi\u00f3n superar\u00e1 los 39 mdp"},"content":{"rendered":"<p>Para brindar mejores servicios a los meridanos, el alcalde, Mauricio Vila Dosal, entreg\u00f3 esta ma\u00f1ana nuevo parque vehicular a las direcciones de Obras P\u00fablicas y Servicios P\u00fablicos Municipales en el que el Ayuntamiento invirti\u00f3 casi $8 millones.<\/p>\n<p>Adem\u00e1s, anticip\u00f3 que est\u00e1 en tr\u00e1mite la adquisici\u00f3n de nuevos veh\u00edculos y equipo para ambas direcciones, con lo que la inversi\u00f3n en este rubro se elevar\u00e1 a casi $39 millones.<\/p>\n<p>Dijo que la entrega de veh\u00edculos y equipo responde a la necesidad de contar con mejores y m\u00e1s modernos equipos, que ayuden a hacer m\u00e1s eficiente el  trabajo.<\/p>\n<p>Enfatiz\u00f3 que M\u00e9rida ha crecido de manera considerable en los \u00faltimos 25 a\u00f1os, per\u00edodo en el que pas\u00f3 de 8 mil a 25 mil hect\u00e1reas, extensi\u00f3n similar a la de la zona metropolitana de Guadalajara, con la diferencia de que ah\u00ed viven 5 millones de personas y aqu\u00ed son poco menos de un mill\u00f3n.<\/p>\n<p>Esto implica, explic\u00f3, que en M\u00e9rida la poblaci\u00f3n est\u00e1 m\u00e1s dispersa y en consecuencia es necesario recorrer mayores distancias para llevarles los servicios.<\/p>\n<p>Durante la entrega, Vila Dosal subray\u00f3 que a pesar de las restricciones presupuestales de este a\u00f1o que ha sido dif\u00edcil econ\u00f3micamente, el Ayuntamiento invierte en servicios y obras p\u00fablicas para seguir brindando atenci\u00f3n de calidad.<\/p>\n<p>El alcalde precis\u00f3 que hoy se entregan a la direcci\u00f3n de Obras P\u00fablica seis camionetas doble cabina, con valor de $1.812,558 y una maquinaria perforadora que tuvo un costo de $1.523,080, de modo que el gasto total fue de $3.335,638.<\/p>\n<p>Ya est\u00e1n en proceso de licitaci\u00f3n, a\u00f1adi\u00f3, nuevas adquisiciones para Obras P\u00fablicas: 7 camiones de volteo de 3 metros c\u00fabicos, 6 placas vibratorias, 1 compresor y 1 tanque de almacenamiento de 20 mil litros para emulsi\u00f3n asf\u00e1ltica, 1 retroexcavadora, entre otros equipos. <\/p>\n<p>En cuanto a Servicios P\u00fablicos Municipales, hoy recibi\u00f3  23 motocicletas adquiridas con una inversi\u00f3n de $411,700, 1 cami\u00f3n de redilas ($463,199.99), 2 camiones de 3 toneladas con caja de volteo de 10 metros c\u00fabicos ($1.163,000) y 1 volquete de 14 metros c\u00fabicos con gr\u00faa hidr\u00e1ulica ($2.344,360). La inversi\u00f3n total ascendi\u00f3 a  $4.382,259.99.<\/p>\n<p>Tambi\u00e9n est\u00e1n en proceso de compra una m\u00e1quina perforadora con un valor superior a los $7  millones y 2 astilladoras, 2 camiones de 10 toneladas rabones, y cami\u00f3n gr\u00faa para alumbrado, 1 camioneta doble cabina, 1 cami\u00f3n de redilas de 3 toneladas, 2 volquetes de 3 toneladas, 1 cami\u00f3n compactador, entre otros veh\u00edculos y equipos. <\/p>\n<p>Estas unidades permitir\u00e1n mejor atenci\u00f3n a reportes, mejor organizaci\u00f3n de los trabajos cotidianos y reforzar\u00e1n la capacidad de supervisi\u00f3n de las \u00e1reas de V\u00edas Terrestres,  Mantenimiento Vial, Electrificaci\u00f3n y Agua Potable, Parques y Jardines, Aseo Urbano, Panteones y Servicios Generales, entre otros.<\/p>\n<p>El total de la inversi\u00f3n en las unidades que hoy entregamos es de casi $8 millones  y cuando terminemos con las dem\u00e1s entregas, en los pr\u00f3ximos meses, habremos invertido s\u00f3lo en este a\u00f1o $39 millones en veh\u00edculos y equipo para las direcciones de Obras P\u00fablicas y Servicios P\u00fablicos Municipales.<\/p>\n<p>Vila Dosal hizo un reconocimiento al desempe\u00f1o de los 2,100 trabajadores de Servicios P\u00fablicos y 350 de Obras P\u00fablicas porque su trabajo de todos los d\u00edas por la ciudad ha sido fundamental para la ciudad.<\/p>\n<p>\u2014Si hoy somos la ciudad con la mejor calidad de vida del pa\u00eds es s\u00f3lo el reflejo de ese trabajo y ese empe\u00f1o \u2014expres\u00f3.<\/p>\n<p>En el acto intervino tambi\u00e9n C\u00e9sar Boj\u00f3rquez Zapata, coordinador general de Funcionamiento Urbano. Al final Mauricio Vila entreg\u00f3  de modo simb\u00f3lico de las llaves de los nuevos veh\u00edculos a los operadores.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Mauricio Vila entrega nuevo parque vehicular a Obras P\u00fablicas y Servicios P\u00fablicos Municipales - Inversi\u00f3n superar\u00e1 los 39 mdp' data-link='https:\/\/visionpeninsular.com\/mid\/2191\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Para brindar mejores servicios a los meridanos, el alcalde, Mauricio Vila Dosal, entreg\u00f3 esta ma\u00f1ana nuevo parque vehicular a las direcciones de Obras P\u00fablicas y Servicios P\u00fablicos Municipales en el que el Ayuntamiento invirti\u00f3 casi $8 millones. Adem\u00e1s, anticip\u00f3 que est\u00e1 en tr\u00e1mite la adquisici\u00f3n de nuevos veh\u00edculos y equipo para ambas direcciones, con lo &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2192,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49],"tags":[41,40],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/2191"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=2191"}],"version-history":[{"count":2,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/2191\/revisions"}],"predecessor-version":[{"id":2194,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/2191\/revisions\/2194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/2192"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=2191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=2191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}