{"id":206020,"date":"2025-08-18T14:59:26","date_gmt":"2025-08-18T19:59:26","guid":{"rendered":"https:\/\/visionpeninsular.com\/mid\/?p=206020"},"modified":"2025-08-18T14:59:30","modified_gmt":"2025-08-18T19:59:30","slug":"cecilia-acerca-a-las-juventudes-con-la-feria-de-empleo-mi-primera-chamba","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/cecilia-acerca-a-las-juventudes-con-la-feria-de-empleo-mi-primera-chamba\/","title":{"rendered":"Cecilia acerca a las juventudes con la feria de empleo \u201cMi Primera Chamba\u201d"},"content":{"rendered":"\n<p>M\u00e9rida, 18 de agosto, 2025.- Con el objetivo de acercar a las juventudes meridanas a oportunidades laborales, de servicio social y pr\u00e1cticas profesionales, el Ayuntamiento de M\u00e9rida, encabezado por la alcaldesa Cecilia Patr\u00f3n Laviada, realiz\u00f3 con \u00e9xito la Feria del Empleo \u201cMi Primera Chamba\u201d en el Centro Cultural Olimpo.<\/p>\n\n\n\n<p>El evento reuni\u00f3 a m\u00e1s de 23 empresas de distintos sectores que ofrecieron vacantes y espacios de vinculaci\u00f3n, reafirmando el compromiso municipal con el impulso del talento joven y su desarrollo integral.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"600\" height=\"363\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-primera.jpg\" alt=\"\" class=\"wp-image-206023\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-primera.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-primera-300x182.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p>\u201cLas y los j\u00f3venes son el motor del cambio social y la fuerza que impulsa el desarrollo de nuestra ciudad. Desde el Ayuntamiento impulsamos una nueva forma de gobernar que reconoce su talento como punta de lanza para una M\u00e9rida m\u00e1s pr\u00f3spera y preparada\u201d, afirm\u00f3 Cecilia Patr\u00f3n durante la inauguraci\u00f3n.<\/p>\n\n\n\n<p>La edil estuvo acompa\u00f1ada de Arturo Le\u00f3n Itz\u00e1, director de Desarrollo Social y Combate a la Pobreza, quien destac\u00f3 que la Feria \u201cMi Primera Chamba\u201d se enmarca en el Mes de la Juventud 2025, pero tambi\u00e9n se suma a las acciones permanentes del Ayuntamiento para generar espacios de vinculaci\u00f3n entre j\u00f3venes y el sector privado.<\/p>\n\n\n\n<p>Adem\u00e1s de los stands empresariales, la feria ofreci\u00f3 pl\u00e1ticas y talleres de orientaci\u00f3n profesional, incluyendo conferencias sobre herramientas digitales, marca personal y empleabilidad. Entre los ponentes destac\u00f3 F\u00e1tima Baeza, conocida como \u201cMiss Fati Tips\u201d y embajadora de Canva, quien comparti\u00f3 estrategias pr\u00e1cticas para el desarrollo profesional.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"600\" height=\"393\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-joven.jpg\" alt=\"\" class=\"wp-image-206024\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-joven.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2025\/08\/chamba-joven-300x197.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p>El evento tambi\u00e9n incluy\u00f3 un m\u00f3dulo informativo sobre servicio social y pr\u00e1cticas profesionales en dependencias municipales, ampliando el abanico de oportunidades para la juventud.<\/p>\n\n\n\n<p>Entre las empresas participantes estuvieron Grupo Rocasa, Peninsular Holiday Inn &amp; Suites M\u00e9rida, Mercado Libre, Millet Industria de Vidrio, Soriana Gran Plaza, Yucat\u00e1n Country Club, entre otras.<\/p>\n\n\n\n<p>La alcaldesa subray\u00f3 que este encuentro fue m\u00e1s que una feria de empleo: \u201cEs un di\u00e1logo abierto. Las empresas conocen el talento de nuestra juventud y los j\u00f3venes descubren las oportunidades que M\u00e9rida les ofrece, ampliando sus horizontes profesionales\u201d.<\/p>\n\n\n\n<p>El evento cont\u00f3 tambi\u00e9n con la presencia de Mauricio D\u00edaz Montalvo, director de Prosperidad y Bienestar Econ\u00f3mico; la diputada Manuela Cocom Bolio y Luis Fernando Castillo Godoy, jefe del Departamento de Juventud del Ayuntamiento.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Cecilia acerca a las juventudes con la feria de empleo \u201cMi Primera Chamba\u201d' data-link='https:\/\/visionpeninsular.com\/mid\/cecilia-acerca-a-las-juventudes-con-la-feria-de-empleo-mi-primera-chamba\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, 18 de agosto, 2025.- Con el objetivo de acercar a las juventudes meridanas a oportunidades laborales, de servicio social y pr\u00e1cticas profesionales, el Ayuntamiento de M\u00e9rida, encabezado por la alcaldesa Cecilia Patr\u00f3n Laviada, realiz\u00f3 con \u00e9xito la Feria del Empleo \u201cMi Primera Chamba\u201d en el Centro Cultural Olimpo. El evento reuni\u00f3 a m\u00e1s de &hellip;<\/p>\n","protected":false},"author":5,"featured_media":206022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49,37],"tags":[41,5668,49817,49816],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/206020"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=206020"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/206020\/revisions"}],"predecessor-version":[{"id":206025,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/206020\/revisions\/206025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/206022"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=206020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=206020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=206020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}