{"id":201871,"date":"2025-04-15T13:46:42","date_gmt":"2025-04-15T18:46:42","guid":{"rendered":"https:\/\/visionpeninsular.com\/mid\/?p=201871"},"modified":"2025-04-15T13:46:45","modified_gmt":"2025-04-15T18:46:45","slug":"nombrado-jacinto-sosa-novelo-nuevo-director-de-aty","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/nombrado-jacinto-sosa-novelo-nuevo-director-de-aty\/","title":{"rendered":"Nombrado Jacinto Sosa Novelo nuevo director de ATY"},"content":{"rendered":"\n<p>M\u00e9rida, 15 de abril, 2025.- En una sesi\u00f3n plenaria llevada a cabo en el Congreso del Estado, Jacinto Sosa Novelo fue designado como &nbsp;el nuevo director de la Agencia de Transporte de Yucat\u00e1n (ATY con 33 votos a favor, tomando el compromiso en el mismo recinto legislativo reafirmando su deber para impulsar un servicio de transporte p\u00fablico seguro, moderno y sustentable en beneficio de las y los yucatecos.<\/p>\n\n\n\n<p>El nuevo titular fungi\u00f3 hasta \u00a0la fecha como encargado del Despacho de la Agencia de Transporte de Yucat\u00e1n y como director de Transporte de la misma y cuenta con experiencia en el servicio como secretario t\u00e9cnico de la Comisi\u00f3n Municipal de Transporte en el Ayuntamiento de M\u00e9rida.<\/p>\n\n\n\n<p>Al respecto, el diputado Daniel Gonz\u00e1lez Quintal asegur\u00f3 que la persona que lidere la Agencia de Transporte debe tener experiencia t\u00e9cnica, sensibilidad social y capacidad de di\u00e1logo.<\/p>\n\n\n\n<p>\u201cNecesitamos mantener una ATY cercana a los usuarios, que escuche, que atienda, que resuelva\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Por su parte, el diputado de PAN, \u00c1lvaro Cetina Puerto, asegur\u00f3 que desde la bancada que representa daban un voto de confianza a la persona que figure como nuevo titular de la Agencia.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Nombrado Jacinto Sosa Novelo nuevo director de ATY' data-link='https:\/\/visionpeninsular.com\/mid\/nombrado-jacinto-sosa-novelo-nuevo-director-de-aty\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, 15 de abril, 2025.- En una sesi\u00f3n plenaria llevada a cabo en el Congreso del Estado, Jacinto Sosa Novelo fue designado como &nbsp;el nuevo director de la Agencia de Transporte de Yucat\u00e1n (ATY con 33 votos a favor, tomando el compromiso en el mismo recinto legislativo reafirmando su deber para impulsar un servicio de &hellip;<\/p>\n","protected":false},"author":5,"featured_media":201873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49,37],"tags":[39343,185,46002,47621],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/201871"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=201871"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/201871\/revisions"}],"predecessor-version":[{"id":201874,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/201871\/revisions\/201874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/201873"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=201871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=201871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=201871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}