{"id":173344,"date":"2023-07-04T21:05:29","date_gmt":"2023-07-05T02:05:29","guid":{"rendered":"https:\/\/visionpeninsular.com\/mid\/?p=173344"},"modified":"2023-07-04T21:05:30","modified_gmt":"2023-07-05T02:05:30","slug":"mas-alla-de-priismos-panismos-o-perredismos-los-yucatecos-de-bien-debemos-enfilarnos-en-la-misma-fila-de-las-mismas-causas-barrera-concha","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/mas-alla-de-priismos-panismos-o-perredismos-los-yucatecos-de-bien-debemos-enfilarnos-en-la-misma-fila-de-las-mismas-causas-barrera-concha\/","title":{"rendered":"\u201cM\u00e1s all\u00e1 de pri\u00edsmos, panismos o perredismos, los yucatecos de bien debemos enfilarnos en la misma fila, de las mismas causas: Barrera Concha"},"content":{"rendered":"\n<p>Debido a la desbandada de priistas a nivel nacional y si el Partido Revolucionario Institucional (PRI), sigue siendo una opci\u00f3n para una alianza en el estado, el alcalde de M\u00e9rida, Ren\u00e1n Barrera Concha, declar\u00f3 que ser\u00e1 una decisi\u00f3n de los dirigentes, pero lo verdaderamente importante es trabajar en torno a un mismo objetivo independientemente de colores y bandos.<\/p>\n\n\n\n<p>Como se sabe, el pasado lunes representantes tricolores de toda la vida como Miguel \u00c1ngel Osorio Chong y Claudia Ruiz Massieu, renunciaron a esta agrupaci\u00f3n, entre otros integrantes.<\/p>\n\n\n\n<p>\u201cCreo que independientemente de las circunstancias particulares de cada partido, hoy se busca que haya una determinaci\u00f3n de lo que queremos que pase en Yucat\u00e1n y eso abre la puerta a que todos aquellos que les preocupa la llegada de un modelo de gobierno similar a otros estados nos podamos unir en torno a un mismo objetivo, m\u00e1s all\u00e1 de panismos, pri\u00edsmos o perredismos, lo que tenemos que hacer los yucatecos de bien, es enfilarnos en la misma fila, de las mismas causas, que es defender la seguridad y educaci\u00f3n, as\u00ed como las condiciones de libertad para los yucatecos\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Asimismo, Barrera Concha consider\u00f3 que m\u00e1s que pensar si aporta o resta el PRI a una probable alianza estatal, habr\u00e1 que determinarlo como est\u00e9 la configuraci\u00f3n al momento de tomar las decisiones.<\/p>\n\n\n\n<p>\u201cHay una disposici\u00f3n de las dirigencias para sentarse a las mesas a construir una posibilidad, no significa que se concrete, ni mucho menos pueda ser una alianza\u201d, dijo.<\/p>\n\n\n\n<p>Para el alcalde, contrario en lo que pasa a nivel nacional donde se bajan aspirantes, en el \u00e1mbito local aumentan y si esto no contamina a la unidad del PAN, catalog\u00f3 que est\u00e1 muy claro y para entenderlo no hay que ser analista pol\u00edtico.<\/p>\n\n\n\n<p>\u201cEl proyecto que he dicho que quiero encabezar en el momento en que el partido abra las convocatorias ah\u00ed voy a estar. Si tenemos objetivos comunes no tiene porque haber divisi\u00f3n, si lo que se est\u00e1 buscando es otro objetivo seguramente habr\u00e1 alg\u00fan tipo de decisi\u00f3n, yo conf\u00edo que no ser\u00e1 as\u00ed y ya llegar\u00e1n los tiempos para ver las intenciones de los participantes\u201d, concluy\u00f3.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\u201cM\u00e1s all\u00e1 de pri\u00edsmos, panismos o perredismos, los yucatecos de bien debemos enfilarnos en la misma fila, de las mismas causas: Barrera Concha' data-link='https:\/\/visionpeninsular.com\/mid\/mas-alla-de-priismos-panismos-o-perredismos-los-yucatecos-de-bien-debemos-enfilarnos-en-la-misma-fila-de-las-mismas-causas-barrera-concha\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Debido a la desbandada de priistas a nivel nacional y si el Partido Revolucionario Institucional (PRI), sigue siendo una opci\u00f3n para una alianza en el estado, el alcalde de M\u00e9rida, Ren\u00e1n Barrera Concha, declar\u00f3 que ser\u00e1 una decisi\u00f3n de los dirigentes, pero lo verdaderamente importante es trabajar en torno a un mismo objetivo independientemente de &hellip;<\/p>\n","protected":false},"author":5,"featured_media":173346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49,37],"tags":[37156,5338],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/173344"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=173344"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/173344\/revisions"}],"predecessor-version":[{"id":173347,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/173344\/revisions\/173347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/173346"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=173344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=173344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=173344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}