{"id":148845,"date":"2021-12-03T10:28:07","date_gmt":"2021-12-03T16:28:07","guid":{"rendered":"https:\/\/visionpeninsular.com\/mid\/?p=148845"},"modified":"2021-12-03T10:28:12","modified_gmt":"2021-12-03T16:28:12","slug":"gobierno-del-estado-realiza-la-repavimentacion-de-otros-10-kilometros-criticos-del-periferico-de-merida","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/gobierno-del-estado-realiza-la-repavimentacion-de-otros-10-kilometros-criticos-del-periferico-de-merida\/","title":{"rendered":"Gobierno del Estado realiza la repavimentaci\u00f3n de otros 10 kil\u00f3metros cr\u00edticos del Perif\u00e9rico de M\u00e9rida"},"content":{"rendered":"\n<p><em>&nbsp;-Por instrucciones del Gobernador Mauricio Vila Dosal, el Instituto de Infraestructura Carretera de Yucat\u00e1n (Incay) lleva a cabo estos trabajos, que se suman a los 13.5 kil\u00f3metros que se repavimentaron inicialmente, con lo que ya ser\u00edan, m\u00e1s de 23 kil\u00f3metros intervenidos por la administraci\u00f3n estatal, no obstante, de que se trata de una v\u00eda federal.<\/em><\/p>\n\n\n\n<p><em>&#8211; Estas obras forman parte de las acciones de mejora a la movilidad, entre las que se encuentran las ciclov\u00edas y las obras de infraestructura efectuadas para garantizar la seguridad de peatones y usuarios de la nueva ruta perif\u00e9rico del sistema de transporte \u201cVa y ven\u201d.<\/em><\/p>\n\n\n\n<p>M\u00e9rida, Yucat\u00e1n, 2 de diciembre de 2021.- Para una movilidad m\u00e1s segura y eficiente de las familias yucatecas, el Gobernador Mauricio Vila Dosal instruy\u00f3 al Instituto de Infraestructura Carretera de Yucat\u00e1n (Incay) realizar trabajos de repavimentaci\u00f3n en otros 10 kil\u00f3metros cr\u00edticos del Anillo Perif\u00e9rico de M\u00e9rida, con lo que van a sumar m\u00e1s de 23 kil\u00f3metros de esa importante arteria intervenidos por la actual administraci\u00f3n estatal, no obstante, de que se trata de una v\u00eda federal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-2.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-2.jpg\" alt=\"\" class=\"wp-image-148848\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-2.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-2-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-2-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Hay que recordar que, como parte Programa Conjunto de Mejora a la Movilidad y la Infraestructura Vial, que impulsa el Gobierno del Estado, recientemente se atendieron 13.5 kil\u00f3metros cr\u00edticos del Anillo Perif\u00e9rico de esta capital, los cuales significaban una necesidad impostergable.<\/p>\n\n\n\n<p>Sobre los trabajos que se est\u00e1n llevando actualmente a cabo, el Incay inform\u00f3 que se repavimentar\u00e1n otros 10.3 kil\u00f3metros de esta importante v\u00eda de la capital yucateca, en la que se mejorar\u00e1n 4.5 km del cuerpo interior y 5.8 km del cuerpo exterior a trav\u00e9s de una inversi\u00f3n de 38 millones de pesos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-3.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-3.jpg\" alt=\"\" class=\"wp-image-148849\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-3.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-3-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-3-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Inicialmente, los trabajos se encuentran realiz\u00e1ndose en el tramo que inicia en el kil\u00f3metro 7+400 despu\u00e9s del paso superior peatonal al kil\u00f3metro 9+200, 100 metros antes de subir al paso superior vehicular X\u2019matkuil.<\/p>\n\n\n\n<p>Tambi\u00e9n se est\u00e1 interviniendo el tramo que parte del kil\u00f3metro 9+800 antes de la rampa de bajada del paso superior vehicular X\u2019matkuil hasta el kil\u00f3metro 11+250, frente a las bodegas de Slakami.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-4.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-4.jpg\" alt=\"\" class=\"wp-image-148850\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-4.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-4-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-4-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Otros de los tramos que ser\u00e1n intervenidos como parte de estos trabajos son: en la zona sur del cuerpo exterior del Perif\u00e9rico, del kil\u00f3metro 11+750 en la entrada a la 42 Sur hasta el kil\u00f3metro 13+150, 50 metros antes de la rampa en la entrada a Mulchech\u00e9n.<\/p>\n\n\n\n<p>Asimismo, del kil\u00f3metro 48+500 frente la empresa PCC Airfoils hasta el kil\u00f3metro 49+500 bajo el paso inferior vehicular de Um\u00e1n. Por \u00faltimo, del kil\u00f3metro 48+500 al 0+150 frente a la Academia de Polic\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-5.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-5.jpg\" alt=\"\" class=\"wp-image-148851\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-5.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-5-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-5-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>En cuanto a la zona norte del cuerpo interior de la v\u00eda, los tramos del kil\u00f3metro 38+100, frente a la tienda de antig\u00fcedades \u201cAnacron\u00eda\u201d, al kil\u00f3metro 36+900, a un lado del centro comercial \u201cPapeler\u00eda del Ahorro\u201d. Tambi\u00e9n del kil\u00f3metro 30+500, a la altura de la entrada a la comisar\u00eda de Temoz\u00f3n Norte, al kil\u00f3metro 28+900, frente a la plaza comercial City Center y del kil\u00f3metro 27+640, a 200 metros de la Torre Ori\u00f3n, hasta el kil\u00f3metro 25+940, despu\u00e9s de la gasolinera Gulf de Montecarlo.<\/p>\n\n\n\n<p>La dependencia estatal detall\u00f3 que los trabajos que se realizan consisten en fresado, renivelaci\u00f3n, colocaci\u00f3n de carpeta de concreto y de se\u00f1alamientos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-6.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-6.jpg\" alt=\"\" class=\"wp-image-148852\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-6.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-6-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-6-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p>Estos trabajos forman parte de las acciones de mejora a la movilidad que el Gobierno del Estado lleva a cabo, entre las que se encuentran las ciclov\u00edas y las obras de infraestructura efectuadas para garantizar la seguridad de peatones y usuarios de la ruta perif\u00e9rico del sistema de transporte \u201cVa y ven\u201d, que se puso en marcha el fin de semana pasado. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-7.jpg\"><img loading=\"lazy\" width=\"600\" height=\"399\" src=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-7.jpg\" alt=\"\" class=\"wp-image-148853\" srcset=\"https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-7.jpg 600w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-7-300x200.jpg 300w, https:\/\/visionpeninsular.com\/mid\/wp-content\/uploads\/2021\/12\/pavi-7-310x205.jpg 310w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Gobierno del Estado realiza la repavimentaci\u00f3n de otros 10 kil\u00f3metros cr\u00edticos del Perif\u00e9rico de M\u00e9rida' data-link='https:\/\/visionpeninsular.com\/mid\/gobierno-del-estado-realiza-la-repavimentacion-de-otros-10-kilometros-criticos-del-periferico-de-merida\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp;-Por instrucciones del Gobernador Mauricio Vila Dosal, el Instituto de Infraestructura Carretera de Yucat\u00e1n (Incay) lleva a cabo estos trabajos, que se suman a los 13.5 kil\u00f3metros que se repavimentaron inicialmente, con lo que ya ser\u00edan, m\u00e1s de 23 kil\u00f3metros intervenidos por la administraci\u00f3n estatal, no obstante, de que se trata de una v\u00eda federal. &hellip;<\/p>\n","protected":false},"author":5,"featured_media":148847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49,37],"tags":[185,717,3861,29415],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/148845"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=148845"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/148845\/revisions"}],"predecessor-version":[{"id":148854,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/148845\/revisions\/148854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/148847"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=148845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=148845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=148845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}