{"id":138807,"date":"2021-01-08T12:42:21","date_gmt":"2021-01-08T18:42:21","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=138807"},"modified":"2021-01-08T12:44:29","modified_gmt":"2021-01-08T18:44:29","slug":"la-trova-va-muestra-los-mas-variados-estilos-en-el-merida-fest-2021","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/la-trova-va-muestra-los-mas-variados-estilos-en-el-merida-fest-2021\/","title":{"rendered":"&#8220;La Trova va&#8221;  muestra los m\u00e1s variados estilos en el \u201cM\u00e9rida Fest 2021\u201d"},"content":{"rendered":"\n<p>De la trova cl\u00e1sica a las fusiones, del romanticismo al baile y voces femeninas que expresan su sentir nutren la serie de conciertos \u201cLa Trova Va\u201d que forma parte de la programaci\u00f3n del M\u00e9rida Fest 2021.<\/p>\n\n\n\n<p>En un encuentro con los medios realizado de manera virtual, el Director de Cultura, Antrop. Irving Berl\u00edn Villafa\u00f1a record\u00f3 que el M\u00e9rida Fest vive un tiempo excepcional con una fiesta responsable, sin eventos masivos, y proyectos con aforos controlados.<\/p>\n\n\n\n<p>\u201cElegimos a la trova porque es uno de los elementos vulnerados en esta pandemia junto con la comunidad art\u00edstica, la trova yucateca es bien com\u00fan que nos pertenece a todos y queremos proyectarla\u201d.<\/p>\n\n\n\n<p>De esta forma la serie de conciertos \u201cLa Trova Va\u201d abre un nuevo espacio para disfrutar el talento de artistas locales. La serie de conciertos inicia este viernes 8 con Daniela Rog\u00e1 y Los Cumbancheros desde el auditorio del Centro Cultural Olimpo, a partir de las 19:30 horas.<\/p>\n\n\n\n<p>Al d\u00eda siguiente, s\u00e1bado 9, tres reconocidas cantautoras unir\u00e1n su talento para expresarse; Ang\u00e9lica Balado, Mar\u00eda San Felipe y Mar\u00eda Moctezuma en el concierto \u201cLATrovadoraDA\u201d.La maestra Ang\u00e9lica Balado expuso que poco a poco se han roto las barreras para que las mujeres canten m\u00e1s que solo cosas rom\u00e1nticas.<\/p>\n\n\n\n<p>En la velada se disfrutar\u00e1n tres tipos de estilos: Mar\u00eda Moctezuma, con su trova alternativa con mezclas de rock, reggae y poniendo al frente valores por la naturaleza, y Mar\u00eda San Felipe con temas donde le canta al amor, la libertad, la feminismo. De Ang\u00e9lica se escuchar\u00e1 versatilidades r\u00edtmicas, g\u00e9neros folcl\u00f3ricos y canciones en las que le gusta la s\u00e1tira social que han caracterizado su trabajo.<\/p>\n\n\n\n<p>\u201cSi habr\u00e1 canci\u00f3n rom\u00e1ntica pero se dar\u00e1 libertad a los temas que manifiestan el pensamiento de las mujeres,&nbsp; de nuestras compositoras\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>El viernes 15 llega el concierto \u201cSincretismo. Himno a la Alegr\u00eda\u201d, en el que se escuchar\u00e1n canciones conocidas a nivel internacional nutridas de los elementos de la trova yucateca tradicional. El trovador Jos\u00e9 Dorantes explic\u00f3 que el proyecto se dise\u00f1\u00f3 para reconocer la trova cl\u00e1sica tradicional.<\/p>\n\n\n\n<p>Como invitados estar\u00e1n la joven Estefan\u00eda Dorantes, quien har\u00e1 su debut musical,&nbsp; junto a Chelo Medina y Raki Barrera, mientras que las voces masculinas ser\u00e1n Roberto Espinosa, Jos\u00e9 Dorantes Junior y el anfitri\u00f3n. Para la presentaci\u00f3n se acompa\u00f1ar\u00e1n de m\u00fasica de violines, metales y percusiones.<\/p>\n\n\n\n<p>El \u00faltimo concierto estar\u00e1 a cargo del grupo Yahal Kab con \u201cTrova entre dos mares\u201d, el pr\u00f3ximo s\u00e1bado 23, en el que se compartir\u00e1 la m\u00fasica de trova del golfo con la caribe\u00f1a. El maestro Ricardo Vega, director del conjunto, expuso que es interesante buscar otros procesos creativos de la trova y que los j\u00f3venes sigan&nbsp; enriqueci\u00e9ndola, la hagan atractiva y permanezca vigente en la actualidad con otros sonidos, ritmos y fusiones.<\/p>\n\n\n\n<p>Durante el repertorio se mostrar\u00e1 los lazos musicales con Cuba, pero tambi\u00e9n incluir\u00e1 canciones de compositores cl\u00e1sicos, pasando por \u201cGuty\u201d C\u00e1rdenas, hasta temas de Jorge Buenfil, Pastor Cervera y de trova cubana de la autor\u00eda de Pablo Milan\u00e9s. Entre los temas se escuchar\u00e1 \u201cMadrigal\u201d considerado el primer bolero mexicano, seg\u00fan comparti\u00f3, as\u00ed como \u201cMi morena\u201d, de Armando Rodr\u00edguez Sosa, el estreno de \u201cCalidad\u201d, con letra de Luis P\u00e9rez Sabido, y en homenaje a Armando Manzanero, el tema \u201cAdoro\u201d, con arreglos de Yahal Kab.<\/p>\n\n\n\n<p>El concierto tambi\u00e9n incluir\u00e1 una canci\u00f3n que Ricardo escribi\u00f3 a la ciudad, \u201cPara mi M\u00e9rida, un son\u201d. Los \u00faltimos tres conciertos se realizar\u00e1n en el Palacio de la M\u00fasica a las 19:30 horas.<\/p>\n\n\n\n<p>Para las funciones presenciales se requieren boletos electr\u00f3nicos para garantizar la seguridad de los meridanos y aforo controlado debido a los momentos que se viven. Los accesos se pueden solicitar en www.Tusboletos.mxLos conciertos tambi\u00e9n podr\u00e1n disfrutarse en l\u00ednea a trav\u00e9s de la p\u00e1gina de facebook M\u00e9rida es Cultura.<\/p>\n\n\n\n<p>En www.merida.gob.mx\/meridafest se puede consultar la programaci\u00f3n completa del M\u00e9rida Fest 2021 \u201cLa trova va, una fiesta responsable\u201d.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\"La Trova va\"  muestra los m\u00e1s variados estilos en el \u201cM\u00e9rida Fest 2021\u201d' data-link='https:\/\/visionpeninsular.com\/mid\/la-trova-va-muestra-los-mas-variados-estilos-en-el-merida-fest-2021\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>De la trova cl\u00e1sica a las fusiones, del romanticismo al baile y voces femeninas que expresan su sentir nutren la serie de conciertos \u201cLa Trova Va\u201d que forma parte de la programaci\u00f3n del M\u00e9rida Fest 2021. En un encuentro con los medios realizado de manera virtual, el Director de Cultura, Antrop. Irving Berl\u00edn Villafa\u00f1a record\u00f3 &hellip;<\/p>\n","protected":false},"author":5,"featured_media":138808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[49,37],"tags":[25474,13587,2757,25306],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/138807"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=138807"}],"version-history":[{"count":2,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/138807\/revisions"}],"predecessor-version":[{"id":138810,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/138807\/revisions\/138810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/138808"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=138807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=138807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=138807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}