{"id":132509,"date":"2020-08-15T10:54:21","date_gmt":"2020-08-15T15:54:21","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=132509"},"modified":"2020-08-15T10:54:29","modified_gmt":"2020-08-15T15:54:29","slug":"funcionamiento-parcial-del-paso-deprimido","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/funcionamiento-parcial-del-paso-deprimido\/","title":{"rendered":"Funcionamiento parcial del \u201cpaso deprimido\u201d"},"content":{"rendered":"\n<p>Despu\u00e9s de poco m\u00e1s de dos meses de permanecer cerrado debido a una inundaci\u00f3n,&nbsp; el llamado \u201cpaso deprimido\u201d de Prolongaci\u00f3n Paseo de Montejo con Circuito Colonias, de M\u00e9rida, fue abierto nuevamente a la circulaci\u00f3n de manera parcial.<\/p>\n\n\n\n<p>El carril que va de norte a sur funciona de manera normal, luego de que se aplicaran reparaciones al asfalto y otras labores de reparaci\u00f3n que efectu\u00f3 el Ayuntamiento de M\u00e9rida, en tanto que en el carril &nbsp;que va de sur a norte,&nbsp; sigue en reparaci\u00f3n.<\/p>\n\n\n\n<p>Durante &nbsp;varios d\u00edas, se realizaron labores de desag\u00fce de m\u00e1s de 4 millones de litros del vital l\u00edquido de la v\u00eda que tuvo que ser cerrada debido a la inundaci\u00f3n que generaron las lluvias de la tormenta tropical \u201cCrist\u00f3bal\u201d.<\/p>\n\n\n\n<p>Las \u00faltimas semanas se aplic\u00f3 un sistema modificado de las descargas y de control de las bombas, lo que permiti\u00f3 concluir el desalojo y limpieza de la vialidad.<\/p>\n\n\n\n<p>La comuna precis\u00f3 que la inundaci\u00f3n da\u00f1\u00f3 la superficie vehicular por lo que se efectu\u00f3 un an\u00e1lisis por miembros del colegio de ingenieros civiles de Yucat\u00e1n, especialistas en estructuras, para la atenci\u00f3n de las acciones preventivas.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Funcionamiento parcial del \u201cpaso deprimido\u201d' data-link='https:\/\/visionpeninsular.com\/mid\/funcionamiento-parcial-del-paso-deprimido\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de poco m\u00e1s de dos meses de permanecer cerrado debido a una inundaci\u00f3n,&nbsp; el llamado \u201cpaso deprimido\u201d de Prolongaci\u00f3n Paseo de Montejo con Circuito Colonias, de M\u00e9rida, fue abierto nuevamente a la circulaci\u00f3n de manera parcial. El carril que va de norte a sur funciona de manera normal, luego de que se aplicaran reparaciones &hellip;<\/p>\n","protected":false},"author":5,"featured_media":132512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[50,37],"tags":[23197,23198],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/132509"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=132509"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/132509\/revisions"}],"predecessor-version":[{"id":132513,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/132509\/revisions\/132513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/132512"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=132509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=132509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=132509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}