{"id":131825,"date":"2020-08-05T10:13:54","date_gmt":"2020-08-05T15:13:54","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=131825"},"modified":"2020-08-05T10:14:01","modified_gmt":"2020-08-05T15:14:01","slug":"nl-presenta-denuncia-penal-contra-pemex-por-derrame-en-arroyo-de-cadereyta","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/nl-presenta-denuncia-penal-contra-pemex-por-derrame-en-arroyo-de-cadereyta\/","title":{"rendered":"NL presenta denuncia penal contra Pemex por derrame en arroyo de Cadereyta"},"content":{"rendered":"\n<p>Autoridades de Nuevo Le\u00f3n informaron este martes sobre la presentaci\u00f3n de una denuncia penal en la Fiscal\u00eda estatal en contra de una refiner\u00eda de Petr\u00f3leos Mexicanos (Pemex), por el derrame de hidrocarburos en el arroyo Ayancual, de Cadereyta.<\/p>\n\n\n\n<p>Al realizar inspecciones, detallaron, fueron encontrados hidrocarburos en el cuerpo de agua, da\u00f1ando flora y fauna.<\/p>\n\n\n\n<p><strong>\u201cLa afectaci\u00f3n ser\u00eda incluso a nivel subsuelo, ya que los mantos acu\u00edferos llegan a la presa El Cuchillo, complicando el tratamiento de agua para su consumo humano.<\/strong>&nbsp;Es la primera vez que un Gobierno de Nuevo Le\u00f3n denuncia a una paraestatal federal\u201d, dijo el Secretario de Desarrollo Sustentable, Jos\u00e9 Manuel Vital.<\/p>\n\n\n\n<p>El d\u00eda de ma\u00f1ana, indic\u00f3 el gobierno de Nuevo Le\u00f3n en su comunicado, ser\u00e1 presentada tambi\u00e9n una denuncia en instalaciones de la Fiscal\u00eda General de la Rep\u00fablica.<\/p>\n\n\n\n<p>El 23 de julio pasado, se inform\u00f3 sobre el caso de Salamanca, Guanajuato, donde autoridades municipales tambi\u00e9n presentaron una denuncia por las emisiones de una refiner\u00eda de Pemex en la localidad.<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.animalpolitico.com\/2020\/07\/alerta-a-pobladores-humo-amarillo-en-salamanca-municipio-denuncia-a-refineria-de-pemex\/\" target=\"_blank\">Los pobladores se alarmaron al ver una nube amarilla<\/a>\u00a0que proven\u00eda de la refiner\u00eda. (ANIMAL POLITICO)<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='NL presenta denuncia penal contra Pemex por derrame en arroyo de Cadereyta' data-link='https:\/\/visionpeninsular.com\/mid\/nl-presenta-denuncia-penal-contra-pemex-por-derrame-en-arroyo-de-cadereyta\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Autoridades de Nuevo Le\u00f3n informaron este martes sobre la presentaci\u00f3n de una denuncia penal en la Fiscal\u00eda estatal en contra de una refiner\u00eda de Petr\u00f3leos Mexicanos (Pemex), por el derrame de hidrocarburos en el arroyo Ayancual, de Cadereyta. Al realizar inspecciones, detallaron, fueron encontrados hidrocarburos en el cuerpo de agua, da\u00f1ando flora y fauna. \u201cLa &hellip;<\/p>\n","protected":false},"author":10,"featured_media":131826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[19567],"tags":[79],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/131825"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=131825"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/131825\/revisions"}],"predecessor-version":[{"id":131827,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/131825\/revisions\/131827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/131826"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=131825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=131825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=131825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}