{"id":128252,"date":"2020-06-16T17:31:10","date_gmt":"2020-06-16T22:31:10","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=128252"},"modified":"2020-06-16T17:31:15","modified_gmt":"2020-06-16T22:31:15","slug":"reactivan-las-visitas-en-el-cereso-de-la-ciudad-de-cancun","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/reactivan-las-visitas-en-el-cereso-de-la-ciudad-de-cancun\/","title":{"rendered":"Reactivan las visitas en el Cereso de la ciudad de Canc\u00fan"},"content":{"rendered":"\n<p>Largas filas se observaron durante el primer d\u00eda en las afueras de la&nbsp;<strong>Centro de Reinserci\u00f3n Social<\/strong>&nbsp;(Cereso) al poner de nuevo en marcha las visitas a internos tras casi dos meses de haber sido suspendidas para prevenir contagios masivos por&nbsp;<strong>Covid-19.<\/strong><\/p>\n\n\n\n<p>Desde muy temprano cientos de personas en su mayor\u00eda mujeres intentaban obtener una ficha para poder\u00a0<strong>ingresar y entregar algo de despensa a sus familiares que se est\u00e1n recluidos en el centro penitenciario con sede en esta ciudad,<\/strong>\u00a0soportando en algunos momentos las lluvias.<\/p>\n\n\n\n<p>Varios j\u00f3venes voluntarios de la&nbsp;<strong>Guardia Auxiliar Ciudadano<\/strong>&nbsp;apoyaban en el lugar, para que&nbsp;&nbsp; las mujeres que pretend\u00edan ingresar, lo hagan de manera ordenada, que tuvieran cubre bocas y con la respectiva sana distancia como parte de las medidas de higiene emitidas por la&nbsp;<strong>Secretaria de Salud Estatal.<\/strong><\/p>\n\n\n\n<p>Grupos de 50 personas pasaban por goteo a trav\u00e9s de un t\u00fanel para poder estar un par de horas con sus familiares tras casi dos meses y medio de no verse a consecuencia de la contingencia sanitaria,\u00a0<strong>por lo que se espera que estas vayan en aumento en los pr\u00f3ximos d\u00edas,<\/strong>\u00a0como se hac\u00eda regularmente antes de la suspensi\u00f3n.<\/p>\n\n\n\n<p>Cabe mencionar que las visitas se realizan los d\u00edas lunes, mi\u00e9rcoles y viernes en un horario de 09 de la ma\u00f1ana hasta 16 horas, hasta el momento solo permiten el ingreso de alimentos y algunas despensas por lo que se le pide a la comunidad que acuda a las visitas lo haga con la vestimenta de color rojo y pantal\u00f3n azul de mezclilla.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Reactivan las visitas en el Cereso de la ciudad de Canc\u00fan' data-link='https:\/\/visionpeninsular.com\/mid\/reactivan-las-visitas-en-el-cereso-de-la-ciudad-de-cancun\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Largas filas se observaron durante el primer d\u00eda en las afueras de la&nbsp;Centro de Reinserci\u00f3n Social&nbsp;(Cereso) al poner de nuevo en marcha las visitas a internos tras casi dos meses de haber sido suspendidas para prevenir contagios masivos por&nbsp;Covid-19. Desde muy temprano cientos de personas en su mayor\u00eda mujeres intentaban obtener una ficha para poder\u00a0ingresar &hellip;<\/p>\n","protected":false},"author":1,"featured_media":128254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[39,48],"tags":[21831],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/128252"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=128252"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/128252\/revisions"}],"predecessor-version":[{"id":128255,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/128252\/revisions\/128255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/128254"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=128252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=128252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=128252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}