{"id":10414,"date":"2016-08-22T18:31:58","date_gmt":"2016-08-22T23:31:58","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=10414"},"modified":"2016-08-22T18:31:58","modified_gmt":"2016-08-22T23:31:58","slug":"cultur-anuncia-que-las-principales-zonas-arqueologicas-de-yucatan-tendran-internet-gratis","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/cultur-anuncia-que-las-principales-zonas-arqueologicas-de-yucatan-tendran-internet-gratis\/","title":{"rendered":"CULTUR anuncia que las principales zonas arqueol\u00f3gicas de Yucat\u00e1n tendr\u00e1n Internet  gratis"},"content":{"rendered":"<p>El internet gratuito en las principales zonas arqueol\u00f3gicas de Yucat\u00e1n ya est\u00e1 a prueba y en breve iniciar\u00e1n los trabajos de remodelaci\u00f3n de los paradores tur\u00edsticos con un presupuesto de 36 millones de pesos, como inform\u00f3 el director del Patronato CULTUR, Dafne L\u00f3pez Mart\u00ednez. Dijo adem\u00e1s  que se ha concluido el proyecto ejecutivo para el remozamiento de los paradores de Chich\u00e9n Itz\u00e1, Uxmal, Lol Tun, Ek Balam, El Corchito, Celest\u00fan, Dzibilchalt\u00fan, el Mercado Artesanal de Zac\u00ed, entre otros.<\/p>\n<p> \u201cYa tenemos concluido el proyecto para el remozamiento de los paradores tur\u00edsticos, estamos en la fase final de pruebas para dotar de internet a los principales puntos, ya est\u00e1 montada la infraestructura y estamos en la fase de pruebas y esperamos que en los pr\u00f3ximos d\u00edas se inaugure este compromiso del gobernador Rolando Zapata Bello\u201d, se\u00f1al\u00f3.<\/p>\n<p>L\u00f3pez Mart\u00ednez agreg\u00f3 que, \u201cdurante septiembre estaremos planeando con mayor precisi\u00f3n el a\u00f1o que viene, buscaremos la mejora continua y el mejor servicio al turista. Lo que queremos es que cuando llegue el visitante a los paradores tur\u00edsticos tenga una buena experiencia, salga con muy buen sabor de boca y podamos prestarle los servicios de manera \u00f3ptima\u201d.<\/p>\n<p>En este contexto, el director del Patronato CULTUR ejemplific\u00f3 acciones como las que se ejecutar\u00e1n en las grutas de Balankanch\u00e9 para darle un nuevo impulso a ese espacio, por lo que se realizar\u00e1n acciones de promoci\u00f3n y la remodelaci\u00f3n del centro de servicios; explic\u00f3 que entre los trabajos a ejecutarse est\u00e1n la modernizaci\u00f3n integral del \u00e1rea de exposici\u00f3n y de las luminarias, construcci\u00f3n del acceso a la unidad de servicios, y rehabilitaci\u00f3n de la palapa, ba\u00f1os, letreros y se\u00f1al\u00e9tica.<\/p>\n<p>\u201cBalankanch\u00e9 es un sitio en el que todos podemos disfrutar de la naturaleza y admirar la gran riqueza que nos heredaron los mayas\u201d, expres\u00f3 L\u00f3pez Mart\u00ednez.<br \/>\nEl Patronato CULTUR explic\u00f3 ayer que los paradores tur\u00edsticos cuentan con estacionamiento, taquillas y sanitarios, as\u00ed como oficinas administrativas de CULTUR y del INAH.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='CULTUR anuncia que las principales zonas arqueol\u00f3gicas de Yucat\u00e1n tendr\u00e1n Internet  gratis' data-link='https:\/\/visionpeninsular.com\/mid\/cultur-anuncia-que-las-principales-zonas-arqueologicas-de-yucatan-tendran-internet-gratis\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El internet gratuito en las principales zonas arqueol\u00f3gicas de Yucat\u00e1n ya est\u00e1 a prueba y en breve iniciar\u00e1n los trabajos de remodelaci\u00f3n de los paradores tur\u00edsticos con un presupuesto de 36 millones de pesos, como inform\u00f3 el director del Patronato CULTUR, Dafne L\u00f3pez Mart\u00ednez. Dijo adem\u00e1s que se ha concluido el proyecto ejecutivo para el &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[50],"tags":[547,751,1831],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10414"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=10414"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10414\/revisions"}],"predecessor-version":[{"id":10421,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10414\/revisions\/10421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/10420"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=10414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=10414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=10414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}