{"id":10037,"date":"2016-08-16T19:46:26","date_gmt":"2016-08-17T00:46:26","guid":{"rendered":"http:\/\/visionpeninsular.com\/mid\/?p=10037"},"modified":"2016-08-16T19:46:26","modified_gmt":"2016-08-17T00:46:26","slug":"primer-juicio-oral-por-feminicidio-en-yucatan-fiscalia-pide-50-anos-de-prision-para-acusado","status":"publish","type":"post","link":"https:\/\/visionpeninsular.com\/mid\/primer-juicio-oral-por-feminicidio-en-yucatan-fiscalia-pide-50-anos-de-prision-para-acusado\/","title":{"rendered":"Primer juicio oral por feminicidio en Yucat\u00e1n. Fiscal\u00eda pide 50 a\u00f1os de prisi\u00f3n para  acusado."},"content":{"rendered":"<p>El juzgado segundo de control decret\u00f3 la apertura del procedimiento contra un joven acusado de feminicidio, para el que la Fiscal\u00eda General del estado (FGE) pidi\u00f3 la pena m\u00e1xima de 50 a\u00f1os, en caso de ser encontrado responsable del crimen.<\/p>\n<p>El caso que se juzgar\u00e1 es el de una joven de 18 a\u00f1os de edad, cuyo cuerpo sin vida fue encontrado en diciembre de 2015, entre la maleza de una calle secundaria que lleva a Conkal, en el kil\u00f3metro 3+400 de la carretera M\u00e9rida-Chicxulub Puerto. La muchacha estaba desnuda y presentaba marcas de estrangulamiento.<\/p>\n<p>El Juzgado Segundo de Control hab\u00eda suspendi\u00f3 por tres d\u00edas la audiencia intermedia del caso del asesinato de la joven Martha M. \u00c1. debido a que el acusado, Felipe G. S., inici\u00f3 las pl\u00e1ticas con la Fiscal\u00eda General del Estado para llegar a un acuerdo y se le realice un procedimiento abreviado;el \u00fanico requisito del procedimiento abreviado es que el acusado acepte la responsabilidad en los hechos  que se le imputan, a cambio se le imponga una sentencia menor.<\/p>\n<p>Entrevistado ayer, en el marco del inicio del curso taller Investigaci\u00f3n Criminal Aplicada al Sistema Penal Acusatorio en el auditorio de la FGE, el fiscal Ariel Aldecua, adelant\u00f3 que la madre de la v\u00edctima no estaba de acuerdo en el mecanismo de justicia alternativa.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Primer juicio oral por feminicidio en Yucat\u00e1n. Fiscal\u00eda pide 50 a\u00f1os de prisi\u00f3n para  acusado.' data-link='https:\/\/visionpeninsular.com\/mid\/primer-juicio-oral-por-feminicidio-en-yucatan-fiscalia-pide-50-anos-de-prision-para-acusado\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El juzgado segundo de control decret\u00f3 la apertura del procedimiento contra un joven acusado de feminicidio, para el que la Fiscal\u00eda General del estado (FGE) pidi\u00f3 la pena m\u00e1xima de 50 a\u00f1os, en caso de ser encontrado responsable del crimen. El caso que se juzgar\u00e1 es el de una joven de 18 a\u00f1os de edad, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false},"categories":[50],"tags":[190,666,2165],"_links":{"self":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10037"}],"collection":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/comments?post=10037"}],"version-history":[{"count":1,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10037\/revisions"}],"predecessor-version":[{"id":10039,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/posts\/10037\/revisions\/10039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media\/10038"}],"wp:attachment":[{"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/media?parent=10037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/categories?post=10037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visionpeninsular.com\/mid\/wp-json\/wp\/v2\/tags?post=10037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}